{"id":8,"count":5,"description":"","link":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/","name":"veggie","slug":"veggie","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>veggie Archieven - studenten recepten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"veggie Archieven - studenten recepten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/\" \/>\n<meta property=\"og:site_name\" content=\"studenten recepten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/\",\"url\":\"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/\",\"name\":\"veggie Archieven - studenten recepten\",\"isPartOf\":{\"@id\":\"https:\/\/studentrecipes.be\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/studentrecipes.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"veggie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/studentrecipes.be\/#website\",\"url\":\"https:\/\/studentrecipes.be\/\",\"name\":\"studenten recepten\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/studentrecipes.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/studentrecipes.be\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/studentrecipes.be\/#organization\",\"name\":\"studenten recepten\",\"url\":\"https:\/\/studentrecipes.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/studentrecipes.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/studentrecipes.be\/wp-content\/uploads\/2023\/10\/cropped-cropped-cropped-mes-e1697898826195.webp\",\"contentUrl\":\"https:\/\/studentrecipes.be\/wp-content\/uploads\/2023\/10\/cropped-cropped-cropped-mes-e1697898826195.webp\",\"width\":120,\"height\":120,\"caption\":\"studenten recepten\"},\"image\":{\"@id\":\"https:\/\/studentrecipes.be\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"veggie Archieven - studenten recepten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/","og_locale":"nl_NL","og_type":"article","og_title":"veggie Archieven - studenten recepten","og_url":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/","og_site_name":"studenten recepten","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/","url":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/","name":"veggie Archieven - studenten recepten","isPartOf":{"@id":"https:\/\/studentrecipes.be\/#website"},"breadcrumb":{"@id":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/studentrecipes.be\/index.php\/category\/veggie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studentrecipes.be\/"},{"@type":"ListItem","position":2,"name":"veggie"}]},{"@type":"WebSite","@id":"https:\/\/studentrecipes.be\/#website","url":"https:\/\/studentrecipes.be\/","name":"studenten recepten","description":"","publisher":{"@id":"https:\/\/studentrecipes.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studentrecipes.be\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/studentrecipes.be\/#organization","name":"studenten recepten","url":"https:\/\/studentrecipes.be\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/studentrecipes.be\/#\/schema\/logo\/image\/","url":"https:\/\/studentrecipes.be\/wp-content\/uploads\/2023\/10\/cropped-cropped-cropped-mes-e1697898826195.webp","contentUrl":"https:\/\/studentrecipes.be\/wp-content\/uploads\/2023\/10\/cropped-cropped-cropped-mes-e1697898826195.webp","width":120,"height":120,"caption":"studenten recepten"},"image":{"@id":"https:\/\/studentrecipes.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/studentrecipes.be\/index.php\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studentrecipes.be\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/studentrecipes.be\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/studentrecipes.be\/index.php\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}